{"id":6878,"date":"2020-01-19T15:11:43","date_gmt":"2020-01-19T15:11:43","guid":{"rendered":"http:\/\/diabetes.org.ar\/2020\/?p=6878"},"modified":"2020-07-17T14:42:58","modified_gmt":"2020-07-17T14:42:58","slug":"newsletter-enero","status":"publish","type":"post","link":"http:\/\/diabetes.org.ar\/2020\/newsletter-enero\/","title":{"rendered":"Newsletter Enero"},"content":{"rendered":"[vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb overlay_strength=\u00bb0.3&#8243; shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_link_target=\u00bb_self\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb overlay_strength=\u00bb0.3&#8243; column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column_text]\n<div class=\"items-leading clearfix\">\n<article class=\"item leading-0\">\n<div class=\"content-wrap\">\n<div class=\"entry-info\">\n<div class=\"introtext\">\n<div class=\"entry-header\">\n<h2>Newsletter Enero<\/h2>\n<\/div>\n<div class=\"introtext\">\n<p><strong>Concepto de endotipo para abordar el desaf\u00edo de heterogeneidad de enfermedad en Diabetes Tipo 1.\u00a0<\/strong><\/p>\n<p>En el n\u00famero de enero de la revista\u00a0<em>Diabetes Care<\/em>, Manuela Battaglia, Simi Ahmed y un equipo internacional de colaboradores, utilizando las lecciones de otras enfermedades y los datos recopilados hasta la fecha, presentan el concepto de endotipo con el objetivo de delinear una hoja de ruta a trav\u00e9s de la cual el campo puede incorporar el concepto en la pr\u00e1ctica cl\u00ednica y de laboratorio. Los autores predicen que tal esfuerzo acelerar\u00e1 la implementaci\u00f3n de la medicina de precisi\u00f3n y tiene el potencial de impacto en nuestro enfoque de investigaci\u00f3n traslacional, dise\u00f1o de ensayos y manejo cl\u00ednico.<\/p>\n<p>En el mismo n\u00famero de\u00a0<em>Diabetes Care<\/em>, Maria J. Redondo y Patrick Concannon publican un comentario respecto del trabajo de Battaglia titulado \u201cLa gen\u00e9tica de la diabetes tipo 1 llega a la mayor\u00eda de edad\u201d, en el que resaltan fortalezas y exponen las limitaciones que han encontrado.<\/p>\n<p><em>Diabetes Care 2020;43:5\u201312 (Art\u00edculo original)<br \/>\n<\/em><em>Diabetes Care 2020;43:16\u201318 (Comentario)<\/em><u><br \/>\n<a href=\"http:\/\/diabetes.org.ar\/index.php\/institucional\/biblioteca-virtual\">Ir a la revista\u00a0<\/a><\/u><\/p>\n<p><strong>Riesgo de r\u00e1pido deterioro de la funci\u00f3n renal, mortalidad por todas las causas y eventos cardiovasculares mayores en enfermedad renal cr\u00f3nica no albumin\u00farica en diabetes tipo 2.<\/strong><\/p>\n<p>En un trabajo realizado por Oyunchimeg Buyadaa, Dianna J. Magliano y colaboradores con 10.185 participantes con diabetes tipo 2 enrolados en el estudio ACCORD (<em>Action to Control Cardiovascular Risk in Diabetes<\/em>), con el objetivo de investigar la tasa de progresi\u00f3n de la enfermedad renal cr\u00f3nica no albumin\u00farica (ERC) a la enfermedad renal en etapa terminal (ESKD) o muerte o eventos cardiovasculares mayores (MACE) comparando los fenotipos albumin\u00faricos y no albumin\u00faricos, los autores hallaron que aquellos con ERC no albumin\u00farica mostraron una tasa de disminuci\u00f3n m\u00e1s lenta en eGFR que cualquier otro grupo. Sin embargo, destacan, que estas personas a\u00fan conllevan un mayor riesgo de muerte y MACE que las personas sin ERC.<\/p>\n<p><em>Diabetes Care 2020;43:122\u2013129<br \/>\n<\/em><u><a href=\"http:\/\/diabetes.org.ar\/index.php\/institucional\/biblioteca-virtual\">Ir a la revista<\/a><\/u><\/p>\n<p><strong>Sensibilidad a la insulina y funci\u00f3n hemodin\u00e1mica renal en adultos con diabetes tipo 2 tratados con metformina y funci\u00f3n renal conservada.<\/strong><\/p>\n<p>Erik J.M. van Bommel, Danique Ruiter y colaboradores demostraron por primera vez, utilizando las mejores t\u00e9cnicas disponibles, que el deterioro de la sensibilidad a la insulina est\u00e1 asociado con una disfunci\u00f3n hemodin\u00e1mica intrarrenal en adultos con diabetes tipo 2 tratados con metformina como monoterapia.<\/p>\n<p>La investigaci\u00f3n se realiz\u00f3 con 44 adultos con diabetes tipo 2, 77% hombres, con una media de edad de 63 \u00b1 7 a\u00f1os, un IMC 31,2 \u00b1 4 kg\/m2, y HbA1c de 7,4 \u00b1 0,6 por ciento, sin enfermedad renal manifiesta. Para evaluar la sensibilidad a la insulina se utiliz\u00f3 un clamp hiperinsulin\u00e9mico-eugluc\u00e9mico (infusi\u00f3n de glucosa en mg\/kg magro\/min) y la funci\u00f3n hemodin\u00e1mica renal fue evaluada con clearance de inulina y de \u00e1cido para-aminohip\u00farico (flujo plasm\u00e1tico renal efectivo).<\/p>\n<p><em>Diabetes Care 2020;43:228\u2013234<br \/>\n<\/em><strong><u><a href=\"http:\/\/diabetes.org.ar\/index.php\/institucional\/biblioteca-virtual\">Ir a la revista<\/a><\/u><\/strong><\/p>\n<p><strong>Prevalencia del s\u00edndrome de piernas inquietas y comorbilidades entre pacientes con mellitus diab\u00e9tico tipo 2<\/strong><\/p>\n<p>En un estudio de secci\u00f3n cruzada realizado en Estambul, Bener A. y colaboradores confirman la relaci\u00f3n positiva y la alta prevalencia (22,8%) del s\u00edndrome de piernas inquietas (RLS) entre pacientes con diabetes tipo 2 en atenci\u00f3n primaria de salud.<\/p>\n<p>El an\u00e1lisis present\u00f3 diferencias estad\u00edsticamente significativas entre pacientes con RLS y sin RLS respecto de dificultad para conciliar el sue\u00f1o, sue\u00f1o inadecuado, fatiga en cualquier momento, molestias en las piernas, hipoglucemia, entumecimiento en las piernas, retinopat\u00eda, neuropat\u00eda, nefropat\u00eda, presi\u00f3n arterial alta, depresi\u00f3n, accidente cerebrovascular, anemia, pie diab\u00e9tico, \u00falcera, artritis, enfermedad respiratoria, s\u00edndrome metab\u00f3lico y enfermedad coronaria, IMC, niveles de HbA1c, vitamina D, calcio, creatinina, ayuno glucosa en sangre, lipoprote\u00edna de baja densidad, triglic\u00e9ridos, \u00e1cido \u00farico y presi\u00f3n arterial sist\u00f3lica y diast\u00f3lica.<\/p>\n<p>Los resultados, indican los autores, sugieren que la actividad f\u00edsica se asocia con una mejor percepci\u00f3n de la capacidad funcional y del dolor en pacientes diab\u00e9ticos con RLS y, por lo tanto, se debe fomentar un estilo de vida m\u00e1s activo.<\/p>\n<p><em>J Family Med Prim Care. 2019 Dec 10;8(12):3814-3820. doi: 10.4103\/jfmpc.jfmpc_463_19. eCollection 2019 Dec.<br \/>\n<\/em><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC6924219\/\" target=\"_blank\" rel=\"noopener\">Ver art\u00edculo completo<\/a><\/p>\n<p><strong>Fracturas vertebrales en individuos con diabetes tipo 2.<\/strong><\/p>\n<p>Los hallazgos de una b\u00fasqueda sistem\u00e1tica de informaci\u00f3n con metaan\u00e1lisis realizada por un equipo internacional de profesionales liderados por Fjorda Koromani y Ling Oei del Centro M\u00e9dico de la Universidad Erasmus en Rotterdam, Holanda, que incluy\u00f3 15 estudios involucrando un total de 852.705 hombres y mujeres, sugieren que las personas con diabetes tipo 2 deben ser evaluadas sistem\u00e1ticamente para presencia de fracturas vertebrales (FV) y, como en individuos sin diabetes, su presencia constituye una indicaci\u00f3n para comenzar el tratamiento para osteoporosis a fin de prevenir futuras fracturas.<\/p>\n<p><em>Diabetes Care 2020;43:137\u2013144<\/em><u><br \/>\n<\/u><u><a href=\"http:\/\/diabetes.org.ar\/index.php\/institucional\/biblioteca-virtual\">Ir a la revista<\/a><br \/>\n<\/u><\/p>\n<p><strong>El consumo de marihuana incrementa el riesgo de cetoacidosis en personas con diabetes tipo 1.<\/strong><\/p>\n<p>En una cohorte de 932 adultos con diabetes tipo 1 en los Estados Unidos, donde el consumo medicinal y recreativo de marihuana es legal en varios Estados, Gregory L. Kinney y colaboradores hallaron que el consumo de marihuana duplica el riesgo de cetoacidosis diab\u00e9tica (odds ratio 2.5 [95% CI 1.0\u20135.9]).<\/p>\n<p>Los efectos gastrointestinales de la marihuana no son ampliamente reconocidos y la raz\u00f3n principal es que en la mayor\u00eda de los usuarios el consumo es recreativo. En humanos, est\u00e1 descrito que la marihuana retrasa el vaciamiento g\u00e1strico, reduce la motilidad intestinal como resultado de la inhibici\u00f3n del sistema colin\u00e9rgico intr\u00ednseco y puede producir hiperemesis. Las alteraciones inducidas por la marihuana en la motilidad intestinal, la absorci\u00f3n de alimentos y el tiempo gluc\u00e9mico posprandial pueden ser inesperadas e inconsistentes para el consumidor t\u00edpico de marihuana con diabetes tipo 1.<\/p>\n<p><em>Diabetes Care 2019;42:2237\u20132246<\/em><u><br \/>\n<\/u><u><a href=\"http:\/\/diabetes.org.ar\/index.php\/institucional\/biblioteca-virtual\">Ir a la revista\u00a0<\/a><br \/>\n<\/u><\/p>\n<p><strong>OTRAS NOVEDADES EDITORIALES<\/strong><\/p>\n<p><strong>Consumo latinoamericano de los principales grupos de alimentos: resultados del estudio ELANS.<\/strong><\/p>\n<p>Un equipo de investigadores liderados por Kovalskys I, del\u00a0<em>International Life Science Institute<\/em>\u00a0(ILSI-Argentina) y de la Facultad de Medicina de la Pontifica Universidad Cat\u00f3lica Argentina, realizaron un estudio transversal multic\u00e9ntrico (ELANS -Estudio Latinoamericano de Nutrici\u00f3n y Salud) evaluando el consumo de alimentos de una muestra urbana de 15 a 65 a\u00f1os de 8 pa\u00edses: Argentina, Brasil, Chile, Colombia, Costa Rica, Ecuador, Per\u00fa y Venezuela. Los investigadores hallaron que la calidad de la ingesta de la dieta es deficiente para los grupos de alimentos ricos en nutrientes, lo que sugiere un mayor riesgo de enfermedades no transmisibles (ENT) en la regi\u00f3n urbana de Latinoam\u00e9rica en las pr\u00f3ximas d\u00e9cadas. Estos datos proporcionan informaci\u00f3n relevante y actualizada para tomar acciones urgentes de salud p\u00fablica para mejorar el consumo de alimentos cr\u00edticos para prevenir las ENT.<\/p>\n<p><em>PLoS One. 2019 Dec 26;14(12):e0225101. doi: 10.1371\/journal.pone.0225101. eCollection 2019.<br \/>\n<\/em><u><a href=\"https:\/\/journals.plos.org\/plosone\/article?id=10.1371\/journal.pone.0225101\" target=\"_blank\" rel=\"noopener\">Ver art\u00edculo completo<\/a><\/u><\/p>\n<p><strong>Consenso de la EASD y ADA sobre apps de diabetes para dispositivos m\u00f3viles.<\/strong><\/p>\n<p>En el n\u00famero de enero de\u00a0<em>Diabetes Care<\/em>\u00a0fue publicado un informe de consenso de la Asociaci\u00f3n Europea para el Estudio de la Diabetes (EASD) y del Grupo de Trabajo sobre Tecnolog\u00eda de la Asociaci\u00f3n Americana de Diabetes (ADA) en el que describen los beneficios, desaf\u00edos de las aplicaciones para dispositivos m\u00f3viles sobre diabetes. El documento incluye una lista de recomendaciones para que las agencias reguladoras, las empresas fabricantes, las sociedades profesionales internacionales y nacionales, los organismos de financiaci\u00f3n, los investigadores, los profesionales sanitarios y las personas con diabetes tengan en cuenta.<\/p>\n<p><em>Diabetes Care 2020;43:250\u2013260<\/em><u><br \/>\n<\/u><u><a href=\"http:\/\/diabetes.org.ar\/index.php\/institucional\/biblioteca-virtual\">Ir a la revista\u00a0<\/a><\/u><\/p>\n<p>&nbsp;<\/p>\n<p><strong>El impacto de la diabetes sobre los ingresos hospitalarios m\u00faltiples evitables.<\/strong><\/p>\n<p>Seringa J, Marques AP y colaboradores analizaron los datos de los hospitales p\u00fablicos portugueses desde 2013 a 2015 para admisiones m\u00faltiples por condiciones sensibles de atenci\u00f3n ambulatoria (ACSC) entre adultos de 18 a\u00f1os o m\u00e1s, considerando como ACSC a los pacientes que presentaron dos o m\u00e1s admisiones durante el periodo bajo estudio. Los autores hallaron que la presencia de diabetes incrementa el riesgo de m\u00faltiples admisiones por ACSC 1.49 veces (p\u2009&lt;\u20090,001) en comparaci\u00f3n con los pacientes sin diabetes, y especialmente en adultos j\u00f3venes (entre 18 y 39 a\u00f1os), y destacan que la presencia de diabetes se asocia con una elevada utilizaci\u00f3n de recursos, lo cual subraya la necesidad de implementar pol\u00edticas adecuadas para el manejo de enfermedades cr\u00f3nicas.<\/p>\n<p><em>BMC Health Serv Res. 2019 Dec 27;19(1):1002. doi: 10.1186\/s12913-019-4840-4.<br \/>\n<\/em><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC6935195\/\" target=\"_blank\" rel=\"noopener\"><u>Ver art\u00edculo completo<\/u>\u00a0\u00a0<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Anormalidades en la conectividad de la materia blanca en prediabetes y en diabetes tipo 2: Estudio Maastricht.<\/strong><\/p>\n<p>Los hallazgos de Laura W. Vergoossen, Miranda T. Schram y colaboradores en la cohorte del estudio Maastricht (1361 personas con metabolismo gl\u00facido normal, 348 con prediabetes y 510 con diabetes tipo 2, evaluadas por prueba de tolerancia a la glucosa; 52% hombres; con 59 \u00b1 8 a\u00f1os de edad), indican que la prediabetes y la diabetes tipo 2 est\u00e1n asociadas con menos conexiones en la materia blanca cerebral y una organizaci\u00f3n m\u00e1s d\u00e9bil de las redes de materia blanca. La diabetes tipo 2 se asoci\u00f3 con una mayor comunicabilidad, que a\u00fan no se observ\u00f3 en la prediabetes y puede reflejar el uso de conexiones alternativas en la materia blanca.<\/p>\n<p><em>Diabetes Care 2020;43:201\u2013208<\/em><u><br \/>\n<\/u><u><a href=\"http:\/\/diabetes.org.ar\/index.php\/institucional\/biblioteca-virtual\">Ir a la revista\u00a0<\/a><\/u><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Efectividad de la liraglutida en el largo plazo para el manejo del peso y el control gluc\u00e9mico en diabetes tipo 2.<\/strong><\/p>\n<p>De acuerdo con un estudio de cohorte realizado por Mirabelli M, Chiefari E y colaboradores, la prolongaci\u00f3n del tratamiento con Liraglutida (60 meses) puede conducir a beneficios duraderos en relaci\u00f3n con el peso y el control gluc\u00e9mico, con un mayor impacto en las mujeres. Estos resultados ampl\u00edan y corroboran las observaciones previas, lo que sugiere que el g\u00e9nero per se puede modular la respuesta a la liraglutida. A pesar de los efectos favorables sobre algunos factores de riesgo de enfermedad cardiovascular (ECV) establecidos, el papel en el largo plazo de la liraglutida en la prevenci\u00f3n primaria de ECV en pacientes con diabetes tipo 2 sigue siendo controvertido.<\/p>\n<p><em>Int J Environ Res Public Health. 2019 Dec 27;17(1). pii: E207. doi: 10.3390\/ijerph17010207.<br \/>\n<\/em><a href=\"https:\/\/www.mdpi.com\/1660-4601\/17\/1\/207\" target=\"_blank\" rel=\"noopener\">Ver art\u00edculo completo<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Eficacia y seguridad del antagonista del receptor de glucag\u00f3n RVT-1502 en diabetes tipo 2 no controlada con metformina: un estudio de rango de dosis.<\/strong><\/p>\n<p>En un estudio fase 2, doble ciego, randomizado y controlado con placebo, de 12 semanas de duraci\u00f3n, Jeremy H. Pettus, David D\u2019Alessio y colaboradores hallaron que el antagonismo del receptor de glucag\u00f3n con RVT-1502 reduce significativamente la HbA1c y el nivel de glucosa en ayunas con las dosis de 5, 10 y 15 mg por d\u00eda, con un perfil de seguridad que respalda un mayor desarrollo cl\u00ednico con estudios de mayor duraci\u00f3n.<\/p>\n<p><em>Diabetes Care 2020;43:161\u2013168<\/em><u><br \/>\n<\/u><u><a href=\"http:\/\/diabetes.org.ar\/index.php\/institucional\/biblioteca-virtual\">Ir a la revista\u00a0<\/a><\/u><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Tambi\u00e9n puede interesarle<br \/>\n<\/strong><\/p>\n<p><strong>Horario de comidas, frecuencia de comidas y omisi\u00f3n del desayuno en individuos adultos con diabetes tipo 1: asociaciones con el control gluc\u00e9mico.<br \/>\n<\/strong><a href=\"https:\/\/www.nature.com\/articles\/s41598-019-56541-5%20\" target=\"_blank\" rel=\"noopener\"><u>Ver texto completo<\/u><\/a><\/p>\n<p><strong>Efectos de la hipertensi\u00f3n y la diabetes sobre la enfermedad renal cr\u00f3nica de reciente comienzo: un estudio de cohorte prospectivo.<\/strong><u><br \/>\n<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/31873983\" target=\"_blank\" rel=\"noopener\">Ver texto completo<\/a><\/u><\/p>\n<p><strong>Riesgo de urticaria en ni\u00f1os con diabetes mellitus tipo 1: una cohorte de alcance nacional.<br \/>\n<\/strong><u><a href=\"https:\/\/www.mdpi.com\/1660-4601\/17\/1\/176\" target=\"_blank\" rel=\"noopener\">Ver texto completo<\/a><\/u><\/p>\n<p><strong>Propiedades antidiab\u00e9ticas de la curcumina II: evidencia de estudios in vivo.<\/strong><u><br \/>\n<a href=\"https:\/\/www.mdpi.com\/2072-6643\/12\/1\/58\" target=\"_blank\" rel=\"noopener\">Ver texto completo<\/a><\/u><a href=\"https:\/\/www.mdpi.com\/2072-6643\/12\/1\/58\" target=\"_blank\" rel=\"noopener\">:<\/a><\/p>\n<p><strong>Fracaso para confirmar un efecto hematopoy\u00e9tico inducido por el inhibidor de SGLT2 en ratas no diab\u00e9ticas con anemia renal.<\/strong><u><br \/>\n<a href=\"https:\/\/onlinelibrary.wiley.com\/doi\/abs\/10.1111\/jdi.13205\" target=\"_blank\" rel=\"noopener\">Ver art\u00edculo completo<\/a><\/u><\/p>\n<p><strong>Evaluaci\u00f3n en el largo plazo de inyecciones intrav\u00edtreas de factor de crecimiento endotelial anti-vascular sobre la funci\u00f3n renal en pacientes con y sin enfermedad renal diab\u00e9tica.<\/strong><u><br \/>\n<a href=\"https:\/\/bmcnephrol.biomedcentral.com\/articles\/10.1186\/s12882-019-1650-1\" target=\"_blank\" rel=\"noopener\">Ver art\u00edculo completo<\/a><\/u><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb overlay_strength=\u00bb0.3&#8243; shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_link_target=\u00bb_self\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb overlay_strength=\u00bb0.3&#8243; column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column_text] Newsletter Enero Concepto de endotipo&#8230;<\/p>\n","protected":false},"author":2,"featured_media":7681,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[27],"tags":[],"class_list":{"0":"post-6878","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-editoriales"},"_links":{"self":[{"href":"http:\/\/diabetes.org.ar\/2020\/wp-json\/wp\/v2\/posts\/6878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/diabetes.org.ar\/2020\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/diabetes.org.ar\/2020\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/diabetes.org.ar\/2020\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/diabetes.org.ar\/2020\/wp-json\/wp\/v2\/comments?post=6878"}],"version-history":[{"count":1,"href":"http:\/\/diabetes.org.ar\/2020\/wp-json\/wp\/v2\/posts\/6878\/revisions"}],"predecessor-version":[{"id":6879,"href":"http:\/\/diabetes.org.ar\/2020\/wp-json\/wp\/v2\/posts\/6878\/revisions\/6879"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/diabetes.org.ar\/2020\/wp-json\/wp\/v2\/media\/7681"}],"wp:attachment":[{"href":"http:\/\/diabetes.org.ar\/2020\/wp-json\/wp\/v2\/media?parent=6878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/diabetes.org.ar\/2020\/wp-json\/wp\/v2\/categories?post=6878"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/diabetes.org.ar\/2020\/wp-json\/wp\/v2\/tags?post=6878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}